{"id":411,"count":1,"description":"","link":"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/","name":"thanksgiving","slug":"thanksgiving","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>thanksgiving Archives | Bowman Veterinary Hospital<\/title>\n<meta name=\"description\" content=\"Our veterinary blog covers a broad range of topics pertaining to current and prospective pet owners.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"thanksgiving Archives | Bowman Veterinary Hospital\" \/>\n<meta property=\"og:description\" content=\"Our veterinary blog covers a broad range of topics pertaining to current and prospective pet owners.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/\" \/>\n<meta property=\"og:site_name\" content=\"Bowman Veterinary Hospital\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bowmanvet.com\/blog\/wp-content\/uploads\/2022\/02\/iStock-1124609720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1984\" \/>\n\t<meta property=\"og:image:height\" content=\"1323\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/tag\\\/thanksgiving\\\/\",\"url\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/tag\\\/thanksgiving\\\/\",\"name\":\"thanksgiving Archives | Bowman Veterinary Hospital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/#website\"},\"description\":\"Our veterinary blog covers a broad range of topics pertaining to current and prospective pet owners.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/tag\\\/thanksgiving\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/tag\\\/thanksgiving\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"thanksgiving\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/\",\"name\":\"Bowman Veterinary Hospital\",\"description\":\"Our Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/#organization\",\"name\":\"Bowman Veterinary Hospital\",\"url\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/square-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/square-logo.png\",\"width\":600,\"height\":600,\"caption\":\"Bowman Veterinary Hospital\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bowmanvet.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"thanksgiving Archives | Bowman Veterinary Hospital","description":"Our veterinary blog covers a broad range of topics pertaining to current and prospective pet owners.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"thanksgiving Archives | Bowman Veterinary Hospital","og_description":"Our veterinary blog covers a broad range of topics pertaining to current and prospective pet owners.","og_url":"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/","og_site_name":"Bowman Veterinary Hospital","og_image":[{"width":1984,"height":1323,"url":"https:\/\/www.bowmanvet.com\/blog\/wp-content\/uploads\/2022\/02\/iStock-1124609720.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/","url":"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/","name":"thanksgiving Archives | Bowman Veterinary Hospital","isPartOf":{"@id":"https:\/\/www.bowmanvet.com\/blog\/#website"},"description":"Our veterinary blog covers a broad range of topics pertaining to current and prospective pet owners.","breadcrumb":{"@id":"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bowmanvet.com\/blog\/tag\/thanksgiving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bowmanvet.com\/blog\/"},{"@type":"ListItem","position":2,"name":"thanksgiving"}]},{"@type":"WebSite","@id":"https:\/\/www.bowmanvet.com\/blog\/#website","url":"https:\/\/www.bowmanvet.com\/blog\/","name":"Bowman Veterinary Hospital","description":"Our Blog","publisher":{"@id":"https:\/\/www.bowmanvet.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bowmanvet.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bowmanvet.com\/blog\/#organization","name":"Bowman Veterinary Hospital","url":"https:\/\/www.bowmanvet.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bowmanvet.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bowmanvet.com\/blog\/wp-content\/uploads\/2025\/08\/square-logo.png","contentUrl":"https:\/\/www.bowmanvet.com\/blog\/wp-content\/uploads\/2025\/08\/square-logo.png","width":600,"height":600,"caption":"Bowman Veterinary Hospital"},"image":{"@id":"https:\/\/www.bowmanvet.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bowmanvet.com\/blog\/wp-json\/wp\/v2\/tags\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bowmanvet.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bowmanvet.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bowmanvet.com\/blog\/wp-json\/wp\/v2\/posts?tags=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}